{"id":14197,"date":"2014-05-25T11:09:42","date_gmt":"2014-05-25T09:09:42","guid":{"rendered":"http:\/\/www.sempreviaggiando.com\/?p=14197"},"modified":"2015-11-02T13:40:43","modified_gmt":"2015-11-02T12:40:43","slug":"idees-visitar-madrid-cap-de-setmana","status":"publish","type":"post","link":"https:\/\/www.sempreviaggiando.com\/ca\/2014\/05\/25\/idees-visitar-madrid-cap-de-setmana\/","title":{"rendered":"7 idees per un cap de setmana a Madrid"},"content":{"rendered":"<p>[summary]<strong>Sempre \u00e9s un plaer passar uns dies a Madrid.<\/strong> Tot i que hi ha moltes coses de la gran capital que no entenc (la M30, la M40, la M50, en Rajoy i el Govern espanyol, el Constitucional&#8230;) n&#8217;hi ha d&#8217;altres que m&#8217;encanten: <strong>els seus jardins, la quantitat d&#8217;activitats culturals que hi ha i els edificis monumentals m\u00edtics.<\/strong>[\/summary]<\/p>\n<p>En la nostra \u00faltima <strong>visita a<\/strong> <strong>Madrid<\/strong>, vam tenir uns guies locals de luxe que ens van portar de la m\u00e0 per Madrid per passar 4 dies fenomenals. Si tens pensat<strong> visitar Madrid, a banda\u00a0de visitar\u00a0la Puerta\u00a0del Sol o la plaza Mayor, pren nota\u00a0d&#8217;aquestes 7 idees per aconseguir que la teva visita sigui una mica m\u00e9s local i aut\u00e8ntica.<\/strong> Potser no tindr\u00e0s\u00a0temps de fer-ho tot, per\u00f2 tri\u00efs el que tri\u00efs, t&#8217;ho passar\u00e0s b\u00e9!<\/p>\n<h3>1. Un caprici<\/h3>\n<p>El\u00a0<strong><a title=\"capricho\" href=\"http:\/\/www.esmadrid.com\/es\/portal.do?TR=C&amp;IDR=877\" target=\"_blank\">Parc del Capricho<\/a><\/strong> \u00e9s un caprici a l&#8217;abast de tothom. Entrada gratu\u00efta i visita m\u00e9s que recomanable. Molt ben cuidat, <strong>ideal per passejar i buscar la inspiraci\u00f3<\/strong>. La seva \u00fanica pega: que no es pot entrar menjar ni beguda, aix\u00ed que queden prohibits els picnics.<\/p>\n<h3>2. Veure una obra de teatre o un musical<\/h3>\n<p>Les vegades que he anat al teatre a Madrid m&#8217;ho he passat d&#8217;all\u00f2 m\u00e9s\u00a0b\u00e9. T\u00e9 una bona reputaci\u00f3 (merescuda) pel que fa a <strong>obres de teatre i musicals<\/strong>. Si tens planejat passar almenys un parell de dies a Madrid,<strong> aconsegueix la revista d&#8217;oci per consultar la cartellera<\/strong>. El nostre \u00faltim encert al teatre:\u00a0<strong><a title=\"cavernicola\" href=\"http:\/\/www.cavernicola.es\/\" target=\"_blank\" rel=\"nofollow\">El Cavern\u00edcola<\/a><\/strong>, amb Nancho Novo. Un mon\u00f2leg divertid\u00edssim i d&#8217;una l\u00f2gica aplastant\u00a0que aconsegueix apartar-se dels t\u00f2pics d&#8217;aquest tipus d&#8217;obres sobre homes i dones.<\/p>\n<h3>3. Fer\u00a0un brunch<\/h3>\n<p>Com a Barcelona, Nova York, o qualsevol altra gran ciutat del m\u00f3n, <strong>el brunch a Madrid tamb\u00e9 est\u00e0 de moda.<\/strong> Els nostres &#8220;guies locals&#8221; (gr\u00e0cies Bequi i Gabi) ens van portar a<strong>\u00a0fer el brunch\u00a0al M\u00fcr, un caf\u00e8 nou, modern, molt cuqui<\/strong> i en el qu\u00e8 a m\u00e9s a m\u00e9s coneixien l&#8217;amo. El\u00a0<a title=\"mur madrid\" href=\"http:\/\/murcafe.es\" target=\"_blank\" rel=\"nofollow\">M\u00fcr<\/a> porta poc temps obert per\u00f2 ja \u00e9s <strong>un dels millors llocs de brunch a Madrid<\/strong> segons ens van explicar. I no m&#8217;estranya! Tenen diferents f\u00f3rmules per\u00f2 el millor\u00a0\u00e9s el &#8220;<strong><a title=\"brunch madrid\" href=\"http:\/\/murcafe.es\/brunch\/\" target=\"_blank\" rel=\"nofollow\">Completo<\/a>&#8220;<\/strong> (si hi aneu amb poca gana, millor que compartiu entre dos persones). Despr\u00e9s dels croissants, els panets, el iogurt i els ous ja no ens va quedar cap forat\u00a0per provar una dels seus<strong> deliciosos pastissos que tamb\u00e9 s\u00f3n famosos<\/strong>. Haurem de tornar-hi un dia a berenar!<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1170\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/www.sempreviaggiando.com\\\/ca\\\/2014\\\/05\\\/25\\\/idees-visitar-madrid-cap-de-setmana\\\/&quot;,&quot;likes_blog_id&quot;:12732733}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1170px; height: 562px;\" data-original-width=\"1170\" data-original-height=\"562\" > <div class=\"gallery-group images-1\" style=\"width: 748px; height: 562px;\" data-original-width=\"748\" data-original-height=\"562\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"744\"> <meta itemprop=\"height\" content=\"558\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"19576\" data-orig-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_1.jpg\" data-orig-size=\"1280,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 5&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1398001176&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.12&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"brunch_1\" data-image-description=\"\" data-medium-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_1-300x225.jpg\" data-large-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_1-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_1.jpg?w=744&#038;h=558&#038;ssl=1\" srcset=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_1.jpg 1280w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_1-300x225.jpg 300w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_1-1024x768.jpg 1024w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_1-400x300.jpg 400w\" width=\"744\" height=\"558\" loading=\"lazy\" data-original-width=\"744\" data-original-height=\"558\" itemprop=\"http:\/\/schema.org\/image\" title=\"brunch_1\" alt=\"brunch_1\" style=\"width: 744px; height: 558px;\" \/> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 422px; height: 562px;\" data-original-width=\"422\" data-original-height=\"562\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"418\"> <meta itemprop=\"height\" content=\"558\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"19577\" data-orig-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_2.jpg\" data-orig-size=\"960,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 5&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1398004476&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.12&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"brunch_2\" data-image-description=\"\" data-medium-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_2-225x300.jpg\" data-large-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_2-768x1024.jpg\" src=\"https:\/\/i0.wp.com\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_2.jpg?w=418&#038;h=558&#038;ssl=1\" srcset=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_2.jpg 960w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_2-225x300.jpg 225w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/brunch_2-768x1024.jpg 768w\" width=\"418\" height=\"558\" loading=\"lazy\" data-original-width=\"418\" data-original-height=\"558\" itemprop=\"http:\/\/schema.org\/image\" title=\"brunch_2\" alt=\"brunch_2\" style=\"width: 418px; height: 558px;\" \/> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<h3>4. Anar a dinar\u00a0a Segovia<\/h3>\n<p>A la gent de Madrid li agrada menjar b\u00e9, d&#8217;aix\u00f2 no ens en va quedar cap dubte. I quan dic menjar b\u00e9 dic <strong>menjar <em>cochinillo<\/em>,\u00a0<em>cocidos<\/em>, ous\u00a0remenats<\/strong>&#8230; I per comprovar.ho, <strong>vam anar a Seg\u00f2via.<\/strong>\u00a0Vam veure l&#8217;Aq\u00fceducte i ens hi vam quedar per dinar. Veni, vidi, vinci. <strong>L&#8217;aq\u00fceducte: enormement preci\u00f3s. El menjar: exquisidament delici\u00f3s.<\/strong><\/p>\n<p><strong>Per menjar b\u00e9 a Seg\u00f2via el millor \u00e9s reservar taula<\/strong>, sobretot si \u00e9s temporada tur\u00edstica -sol emplenar-se r\u00e0pid. Quan hi vam anar era Setmana Santa i amb la processons, era impossible passejar amb m\u00e9s d&#8217;un metre d&#8217;espai. Per aix\u00f2, ens vam alegrar en saber que ten\u00edem taula reservada als afores de la ciutat, <strong>a Revenga (a nom\u00e9s 6 km) en un restaurant molt aut\u00e8ntic i local<\/strong>:\u00a0<strong><a title=\"casa mariano\" href=\"http:\/\/www.hospedajecasamariano.com\/restaurante.htm\" target=\"_blank\" rel=\"nofollow\">Casa Mariano<\/a><\/strong>. <strong>La\u00a0t\u00edpica fonda r\u00fastica castellana<\/strong>, <strong>amb men\u00fas diaris a bon preu, molt bon tracte i excel\u00b7lent\u00a0menjar<\/strong>. A m\u00e9s a m\u00e9s, tamb\u00e9 tenen habitacions per a viatgers. Recomanant plenament si passeu per all\u00e0.<strong>\u00a0<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12641\" src=\"http:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/segovia_1.jpg\" alt=\"segovia_1\" width=\"1280\" height=\"960\" srcset=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/segovia_1.jpg 1280w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/segovia_1-300x225.jpg 300w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/segovia_1-1024x768.jpg 1024w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/segovia_1-400x300.jpg 400w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12634\" src=\"http:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/navacerrada-segovia.jpg\" alt=\"navacerrada-segovia\" width=\"1000\" height=\"667\" srcset=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/navacerrada-segovia.jpg 1000w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/navacerrada-segovia-300x200.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><strong>Per anar a Seg\u00f2via teniu dues opcions: anar-hi per l&#8217;autopista o anar-hi per la Sierra<\/strong>. Si teniu temps, el passeig per la Sierra \u00e9s m\u00e9s que recomanable. Podeu parar a <strong>Navacerrada<\/strong> (hi ha un caf\u00e8 per esmorzar). No hi ha\u00a0gaires\u00a0voltes i el cam\u00ed \u00e9s senzill i agradable (m\u00e9s senzill que el Montseny, per exemple).<\/p>\n<p><strong>De tornada a Madrid no oblideu parar a<\/strong>\u00a0<strong><a title=\"la granja\" href=\"http:\/\/es.wikipedia.org\/wiki\/Palacio_Real_de_La_Granja_de_San_Ildefonso\" target=\"_blank\">La Granja de San Ildefonso<\/a><\/strong>, on podreu passejar pels fabulosos <strong>jardins de Palau, com si f\u00f3ssiu a Versailles<\/strong>. Aparcar all\u00e0 \u00e9s complicat per\u00f2 el passeig val la pena, sobretot si les fonts estan enceses.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1170\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/www.sempreviaggiando.com\\\/ca\\\/2014\\\/05\\\/25\\\/idees-visitar-madrid-cap-de-setmana\\\/&quot;,&quot;likes_blog_id&quot;:12732733}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1170px; height: 583px;\" data-original-width=\"1170\" data-original-height=\"583\" > <div class=\"gallery-group images-1\" style=\"width: 390px; height: 583px;\" data-original-width=\"390\" data-original-height=\"583\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"579\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"19571\" data-orig-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-3.jpg\" data-orig-size=\"667,1000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;Francisco Palma&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark III&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1397840376&quot;,&quot;copyright&quot;:&quot;frpalma&quot;,&quot;focal_length&quot;:&quot;160&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"granja-revenga-3\" data-image-description=\"\" data-medium-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-3-200x300.jpg\" data-large-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-3.jpg\" src=\"https:\/\/i0.wp.com\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-3.jpg?w=386&#038;h=579&#038;ssl=1\" srcset=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-3.jpg 667w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-3-200x300.jpg 200w\" width=\"386\" height=\"579\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"579\" itemprop=\"http:\/\/schema.org\/image\" title=\"granja-revenga-3\" alt=\"granja-revenga-3\" style=\"width: 386px; height: 579px;\" \/> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 583px;\" data-original-width=\"390\" data-original-height=\"583\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"579\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"19570\" data-orig-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-2.jpg\" data-orig-size=\"667,1000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;Francisco Palma&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark III&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1397839405&quot;,&quot;copyright&quot;:&quot;frpalma&quot;,&quot;focal_length&quot;:&quot;127&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"granja-revenga-2\" data-image-description=\"\" data-medium-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-2-200x300.jpg\" data-large-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-2.jpg\" src=\"https:\/\/i0.wp.com\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-2.jpg?w=386&#038;h=579&#038;ssl=1\" srcset=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-2.jpg 667w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-2-200x300.jpg 200w\" width=\"386\" height=\"579\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"579\" itemprop=\"http:\/\/schema.org\/image\" title=\"granja-revenga-2\" alt=\"granja-revenga-2\" style=\"width: 386px; height: 579px;\" \/> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 583px;\" data-original-width=\"390\" data-original-height=\"583\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"579\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"19569\" data-orig-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga.jpg\" data-orig-size=\"667,1000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;11&quot;,&quot;credit&quot;:&quot;Francisco Palma&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark III&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1397839500&quot;,&quot;copyright&quot;:&quot;frpalma&quot;,&quot;focal_length&quot;:&quot;187&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"granja-revenga\" data-image-description=\"\" data-medium-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-200x300.jpg\" data-large-file=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga.jpg\" src=\"https:\/\/i0.wp.com\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga.jpg?w=386&#038;h=579&#038;ssl=1\" srcset=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga.jpg 667w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/granja-revenga-200x300.jpg 200w\" width=\"386\" height=\"579\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"579\" itemprop=\"http:\/\/schema.org\/image\" title=\"granja-revenga\" alt=\"granja-revenga\" style=\"width: 386px; height: 579px;\" \/> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<h3>5. Veure una exposici\u00f3<\/h3>\n<p><strong>Amb tants museus \u00e9s gaireb\u00e9 impossible que no hi hagi alguna exposici\u00f3 en cartell que no t&#8217;atraigui.<\/strong> N&#8217;hi ha per a tots els gustos: des d&#8217;art cl\u00e0ssic fins a art modern, passant fins i tot per animaci\u00f3; aquell cap de setmana\u00a0hi havia\u00a0a Madrid l&#8217;<a title=\"exposicion pixar\" href=\"http:\/\/www.agendacentrosobrasociallacaixa.es\/es\/caixaforum-madrid\/exposiciones-temporales-caixaforum-madrid\/pixar\" target=\"_blank\" rel=\"nofollow\"><strong>exposici\u00f3 de Pixar al CaixaForum<\/strong><\/a> (fins al 22 de juny a Madrid, despr\u00e9s a Saragossa ia partir de febrer 2015 a Barcelona).<\/p>\n<h3>6. Escapar-se a Toledo o a Alcal\u00e1 de Henares<\/h3>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12639 size-medium\" src=\"http:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/toledo-1-200x300.jpg\" alt=\"toledo-1\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/toledo-1-200x300.jpg 200w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/toledo-1-682x1024.jpg 682w, https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/toledo-1.jpg 1000w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/strong><\/p>\n<p>Si una cosa \u00fanica t\u00e9 estar a Madrid \u00e9s que est\u00e0s<strong> sempre a un pas de la resta d&#8217;Espanya<\/strong>. <strong>I una de les excursions t\u00edpiques d&#8217;un dia des de Madrid \u00e9s passar el dia\u00a0a Toledo o a Alcal\u00e1 d&#8217;Henares.<\/strong> Hem estat a totes\u00a0dues i estan realment molt b\u00e9 per passar un dia fora de Madrid. Estan a <strong>uns 35-40 minuts de Madrid amb cotxe.<\/strong><\/p>\n<p>Tant Toledo com Alcal\u00e1 tenen centres antics emmurallats i s\u00f3n\u00a0petitons -ideals per\u00a0fer\u00a0caminant. <strong>La meva recomanaci\u00f3: acostar-se a l&#8217;Oficina de Turisme per demanar un mapa i confirmar els horaris de cada visita<\/strong>. Toledo t\u00e9 edificis monumentals preciosos per\u00f2 el millor de la ciutat \u00e9s passejar pels carrerons del Call, veure les cases amb balcons i (si fa bon temps) allunyar-se de la ciutat emmurallada per veure les vistes.\u00a0<a title=\"toledo\" href=\"http:\/\/www.toledo-turismo.com\/es\/plano-tur%C3%AD%C2%ADstico_486\" target=\"_blank\">Mapa de Toledo<\/a>. La ciutat t\u00e9 un <strong>museu dedicat al pintor El Greco<\/strong>; i aquest any\u00a0<a title=\"greco 2014\" href=\"http:\/\/www.elgreco2014.com\/\" target=\"_blank\" rel=\"nofollow\">2014 se celebra el centenari<\/a>\u00a0de la seva mort. <strong>A Alcal\u00e1 de Henares podr\u00e0s visitar la Casa-Museu de Cervantes<\/strong>, la catedral, la Universitat, el Palau arquebisbal &#8230; i per descomptat, aqu\u00ed tamb\u00e9 hi menjar\u00e0s b\u00e9.\u00a0<a title=\"alcal\u00e1 henares\" href=\"http:\/\/www.turismoalcala.es\/images\/plano%20nuevo%20logo.pdf\" target=\"_blank\">Mapa de Alcal\u00e1 de Henares<\/a>.<\/p>\n<h3>7. Ruta de tapes per la Latina<\/h3>\n<p>\u00c9s probable que despr\u00e9s del cochinillo de Seg\u00f2via i de la sopa castellana de Toledo ja no tinguis massa gana, per\u00f2 si alguna nit est\u00e0s a Madrid i et ve de gust menjar alguna cosa local, <strong>la teva millor opci\u00f3 s\u00f3n les tapes. Fes un volt gastron\u00f2mic pel barri de la Latina: Cava Alta i Cava\u00a0Baja<\/strong>\u00a0s\u00f3n els carrers m\u00e9s concorreguts, per\u00f2 si no\u00a0t&#8217;agraden\u00a0les aglomeracions prova amb una <strong>ruta de tapes per &#8220;la Latina Alternativa&#8221;: bars amb molta solera, aut\u00e8ntics, d&#8217;els de tota la vida<\/strong>. Segueix les instruccions detallades per Gastroplan (<a title=\"latina alternativa\" href=\"https:\/\/maps.google.com\/maps\/ms?msid=209612217098806631390.0004d447168d627c863bc&amp;msa=0\" target=\"_blank\">mapa<\/a>\u00a0i\u00a0<a title=\"latina alternativa\" href=\"http:\/\/www.gastroplan.es\/documents\/rutas\/ruta_la-latina-alternativa2.pdf\" target=\"_blank\" rel=\"nofollow\">ruta explicada en PDF<\/a>). No et perdis l&#8217;orella fregida del Mu\u00f1iz!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[summary]Sempre \u00e9s un plaer passar uns dies a Madrid. Tot i que hi ha moltes coses de la gran capital que no entenc (la M30, la M40, la M50, en Rajoy i el Govern espanyol, el Constitucional&#8230;) n&#8217;hi ha d&#8217;altres que m&#8217;encanten: els seus jardins, la quantitat d&#8217;activitats culturals que hi ha i els edificis<\/p>\n<div class=\"read-more-wrapper\"><a class=\"read-more\" href=\"https:\/\/www.sempreviaggiando.com\/ca\/2014\/05\/25\/idees-visitar-madrid-cap-de-setmana\/\" title=\"Read More\"> <span class=\"button \">Read More<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":12640,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bos_mb_destination":[""],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[126],"tags":[],"class_list":["post-14197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rutes-per-espanya"],"acf":[],"jetpack_featured_media_url":"https:\/\/www.sempreviaggiando.com\/wp-content\/uploads\/2014\/05\/DV6B9364.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sempreviaggiando.com\/ca\/wp-json\/wp\/v2\/posts\/14197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sempreviaggiando.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sempreviaggiando.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sempreviaggiando.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sempreviaggiando.com\/ca\/wp-json\/wp\/v2\/comments?post=14197"}],"version-history":[{"count":5,"href":"https:\/\/www.sempreviaggiando.com\/ca\/wp-json\/wp\/v2\/posts\/14197\/revisions"}],"predecessor-version":[{"id":14203,"href":"https:\/\/www.sempreviaggiando.com\/ca\/wp-json\/wp\/v2\/posts\/14197\/revisions\/14203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sempreviaggiando.com\/ca\/wp-json\/wp\/v2\/media\/12640"}],"wp:attachment":[{"href":"https:\/\/www.sempreviaggiando.com\/ca\/wp-json\/wp\/v2\/media?parent=14197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sempreviaggiando.com\/ca\/wp-json\/wp\/v2\/categories?post=14197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sempreviaggiando.com\/ca\/wp-json\/wp\/v2\/tags?post=14197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}